{"id":319,"count":4,"description":"","link":"https:\/\/www.wildlifephotographer.se\/blog\/tag\/morkret\/","name":"M\u00f6rkret","slug":"morkret","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags\/319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts?tags=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}