{"id":247,"count":2,"description":"","link":"https:\/\/www.wildlifephotographer.se\/blog\/tag\/blixt\/","name":"Blixt","slug":"blixt","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts?tags=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}