{"id":1492,"count":1,"description":"","link":"https:\/\/www.wildlifephotographer.se\/blog\/tag\/mittafallet\/","name":"Mitt\u00e5fallet","slug":"mittafallet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags\/1492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts?tags=1492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}