{"id":1101,"count":1,"description":"","link":"https:\/\/www.wildlifephotographer.se\/blog\/tag\/slott\/","name":"Slott","slug":"slott","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags\/1101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts?tags=1101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}