{"id":168169,"date":"2024-01-23T12:58:35","date_gmt":"2024-01-23T11:58:35","guid":{"rendered":"https:\/\/www.wildlifephotographer.se\/blog\/?p=168169"},"modified":"2025-11-27T14:23:48","modified_gmt":"2025-11-27T13:23:48","slug":"december-2023","status":"publish","type":"post","link":"https:\/\/www.wildlifephotographer.se\/blog\/2024\/01\/december-2023\/","title":{"rendered":"December 2023"},"content":{"rendered":"<div id=\"attachment_168039\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-168039\" class=\"size-large wp-image-168039\" src=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-640x427.jpg\" alt=\"V\u00e5mhus kyrka\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-640x427.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-1536x1024.jpg 1536w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2023\/12\/elobe_720868-2.jpg 1800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-168039\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS M3 (15mm, f\/8, 1\/60 sec, ISO125)<br><\/span> V\u00e5mhus kyrka<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":168039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[928],"tags":[929,930],"class_list":["post-168169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monthly","tag-manadens-foto","tag-photo-of-the-month","category-928-id","post-seq-1","post-parity-odd","meta-position-corners","fix"],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/168169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/comments?post=168169"}],"version-history":[{"count":1,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/168169\/revisions"}],"predecessor-version":[{"id":168170,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/168169\/revisions\/168170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media\/168039"}],"wp:attachment":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media?parent=168169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/categories?post=168169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags?post=168169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}