{"id":165376,"date":"2022-02-01T12:21:44","date_gmt":"2022-02-01T11:21:44","guid":{"rendered":"https:\/\/www.wildlifephotographer.se\/blog\/?p=165376"},"modified":"2025-12-02T13:30:35","modified_gmt":"2025-12-02T12:30:35","slug":"january-2022","status":"publish","type":"post","link":"https:\/\/www.wildlifephotographer.se\/blog\/2022\/02\/january-2022\/","title":{"rendered":"January 2022"},"content":{"rendered":"<div id=\"attachment_165310\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-165310\" class=\"size-large wp-image-165310\" src=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2-640x411.jpg\" alt=\"Guldskimmer \u00f6ver sj\u00f6n\" width=\"640\" height=\"411\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2-640x411.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2-300x193.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2-200x128.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2-96x62.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2022\/01\/elobe_715583-2.jpg 1500w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-165310\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 5D Mark IV (200mm, f\/7.1, 1\/200 sec, ISO640)<br><\/span> Guldskimmer \u00f6ver sj\u00f6n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":165310,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[928],"tags":[929,930],"class_list":["post-165376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monthly","tag-manadens-foto","tag-photo-of-the-month","category-928-id","post-seq-1","post-parity-odd","meta-position-corners","fix"],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/165376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/comments?post=165376"}],"version-history":[{"count":2,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/165376\/revisions"}],"predecessor-version":[{"id":165380,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/165376\/revisions\/165380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media\/165310"}],"wp:attachment":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media?parent=165376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/categories?post=165376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags?post=165376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}