{"id":158202,"date":"2018-07-06T08:42:32","date_gmt":"2018-07-06T06:42:32","guid":{"rendered":"http:\/\/www.wildlifephotographer.se\/blog\/?p=158202"},"modified":"2025-11-29T08:23:51","modified_gmt":"2025-11-29T07:23:51","slug":"midsommarfirande-i-vamhus","status":"publish","type":"post","link":"https:\/\/www.wildlifephotographer.se\/blog\/2018\/07\/midsommarfirande-i-vamhus\/","title":{"rendered":"Midsommarfirande i V\u00e5mhus"},"content":{"rendered":"<p>N\u00e5gra bilder fr\u00e5n ett mycket trevligt midsommarfirande p\u00e5 V\u00e5mhus Gammelg\u00e5rd&#8230;<\/p>\n<div id=\"attachment_158020\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158020\" class=\"size-large wp-image-158020\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-640x426.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-640x426.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738-150x100.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697738.jpg 1250w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158020\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (17mm, f\/6.3, 1\/500 sec, ISO100)<br><\/span> Midsommarfest p\u00e5 V\u00e5mhus Gammelg\u00e5rd<\/p><\/div>\n<div id=\"attachment_158021\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158021\" class=\"size-large wp-image-158021\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-640x426.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-640x426.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780-150x100.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697780.jpg 1250w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158021\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (17mm, f\/7.1, 1\/400 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n<div id=\"attachment_158022\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158022\" class=\"size-large wp-image-158022\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-640x426.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-640x426.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803-150x100.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697803.jpg 1250w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158022\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (40mm, f\/11, 1\/200 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n<div id=\"attachment_158019\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158019\" class=\"size-large wp-image-158019\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-640x426.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-640x426.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736-150x100.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697736.jpg 1250w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158019\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (40mm, f\/5.6, 1\/500 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n<div id=\"attachment_158023\" style=\"width: 437px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158023\" class=\"size-large wp-image-158023\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-427x640.jpg\" alt=\"\" width=\"427\" height=\"640\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-427x640.jpg 427w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-133x200.jpg 133w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-200x300.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-64x96.jpg 64w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818-150x225.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697818.jpg 620w\" sizes=\"auto, (max-width: 427px) 100vw, 427px\" \/><\/a><p id=\"caption-attachment-158023\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (17mm, f\/11, 1\/200 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n<div id=\"attachment_158024\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158024\" class=\"size-large wp-image-158024\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-640x480.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-640x480.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-200x150.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-300x225.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-96x72.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858-150x113.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697858.jpg 1240w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158024\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (17mm, f\/11, 1\/400 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n<div id=\"attachment_158025\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-158025\" class=\"wp-image-158025 size-large\" src=\"http:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-640x426.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-640x426.jpg 640w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-200x133.jpg 200w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-300x200.jpg 300w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-96x64.jpg 96w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870-150x100.jpg 150w, https:\/\/www.wildlifephotographer.se\/blog\/wp-content\/uploads10\/2018\/07\/elobe_697870.jpg 1250w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-158025\" class=\"wp-caption-text\"><span style=\"display:block; color:#888; font-size:small; font-weight:normal;\">Canon EOS 7D Mark II (33mm, f\/11, 1\/200 sec, ISO100)<br><\/span> &#8230;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e5gra bilder fr\u00e5n ett mycket trevligt midsommarfirande p\u00e5 V\u00e5mhus Gammelg\u00e5rd&#8230;<\/p>\n","protected":false},"author":2,"featured_media":158024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[261,21,49],"tags":[1248,112,951,70],"class_list":["post-158202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-singles","category-culture","category-summer","tag-gammelgard","tag-kultur","tag-midsommar","tag-vamhus","category-261-id","category-21-id","category-49-id","post-seq-1","post-parity-odd","meta-position-corners","fix"],"_links":{"self":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/158202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/comments?post=158202"}],"version-history":[{"count":1,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/158202\/revisions"}],"predecessor-version":[{"id":158203,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/posts\/158202\/revisions\/158203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media\/158024"}],"wp:attachment":[{"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/media?parent=158202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/categories?post=158202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildlifephotographer.se\/blog\/wp-json\/wp\/v2\/tags?post=158202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}